{"id":7091,"date":"2011-11-04T08:39:30","date_gmt":"2011-11-04T08:39:30","guid":{"rendered":"http:\/\/www.weltweit-urlaub.de\/blog\/?p=7091"},"modified":"2014-03-05T16:47:49","modified_gmt":"2014-03-05T15:47:49","slug":"der-grosse-stein-von-tonnenheide","status":"publish","type":"post","link":"https:\/\/www.weltweit-urlaub.de\/blog\/der-grosse-stein-von-tonnenheide\/","title":{"rendered":"Der Gro\u00dfe Stein von Tonnenheide"},"content":{"rendered":"<p>Wir erreichen den <strong>Gro\u00dfen Stein<\/strong> \u00fcber die Stra\u00dfe Rahden &#8211; Diepenau im sch\u00f6nen <a target=\"_blank\" href=\"https:\/\/www.weltweit-urlaub.de\/deutschland\/nordrhein-westfalen\/muehlenkreis\/\" >M\u00fchlenkreis<\/a>. In Tonnenheide &#8211; Heidkamp biegen wir am Wegweiser &#8222;Gro\u00dfer Stein&#8220; links ab. Es ist kaum zu glauben, aber es handelt sich tats\u00e4chlich um einen<strong> Findling<\/strong> aus <a target=\"_blank\" href=\"https:\/\/www.weltweit-urlaub.de\/skandinavien\/\" >Skandinavien<\/a>. Dieser ist 10 m lang, 7 m breit und 3 m hoch. Sein Gewicht betr\u00e4gt 350 Tonnen. Es ist der gr\u00f6\u00dfte Findling Norddeutschlands. Sein Alter betr\u00e4gt etwa <strong>eine Milliarde Jahre<\/strong>. Fast unwahrscheinlich klingt es, dass der Stein gar nicht an dieser Stelle gefunden wurde, sondern im Jahre 1981 hierhin verfrachtet wurde. <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.weltweit-urlaub.de\/blog\/wp-content\/uploads\/windmuehle-tonnenheide.jpg\" alt=\"Windm\u00fchle Tonnenheide\" title=\"Windm\u00fchle Tonnenheide\" width=\"450\" height=\"338\" class=\"aligncenter size-full wp-image-7097\" border=\"1\" \/><br \/>\n<em>Die Windm\u00fchle von Tonnenheide<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.weltweit-urlaub.de\/blog\/wp-content\/uploads\/grosser-stein-tonneheide.jpg\" alt=\"Gro\u00dfer Stein Tonneheide\" title=\"Gro\u00dfer Stein Tonneheide\" width=\"450\" height=\"338\" class=\"aligncenter size-full wp-image-7093\" border=\"1\" \/><br \/>\n<em>Der Gro\u00dfe Stein<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.weltweit-urlaub.de\/blog\/wp-content\/uploads\/tonneheide-grosser-stein.jpg\" alt=\"Tonneheide gro\u00dfer Stein\" title=\"Tonneheide gro\u00dfer Stein\" width=\"450\" height=\"338\" class=\"aligncenter size-full wp-image-7095\" border=\"1\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.weltweit-urlaub.de\/blog\/wp-content\/uploads\/fachwerkhaeuser-tonnenheide.jpg\" alt=\"Fachwerkh\u00e4user Tonnenheide\" title=\"Fachwerkh\u00e4user Tonnenheide\" width=\"450\" height=\"338\" class=\"aligncenter size-full wp-image-7092\" border=\"1\" \/><br \/>\n<em>Auf der Wiese stehen auch einige restaurierte Fachwerkh\u00e4uschen. Nebenan befindet sich noch ein K\u00e4sereibetrieb.<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.weltweit-urlaub.de\/blog\/wp-content\/uploads\/stein-tonnenheide.jpg\" alt=\"Stein Tonnenheide\" title=\"Stein Tonnenheide\" width=\"450\" height=\"338\" class=\"aligncenter size-full wp-image-7094\" border=\"1\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.weltweit-urlaub.de\/blog\/wp-content\/uploads\/tonnenheide-grosser-stein-vorn.jpg\" alt=\"Tonnenheide gro\u00dfer Stein vorn\" title=\"Tonnenheide gro\u00dfer Stein vorn\" width=\"450\" height=\"338\" class=\"aligncenter size-full wp-image-7096\" border=\"1\" \/><\/p>\n<p>&nbsp;<br \/>\n<strong>Hotels im M\u00fchlenkreis und an der M\u00fchlenstra\u00dfe:<\/strong><\/p>\n<p><a target=\"_blank\" href=\"https:\/\/www.weltweit-urlaub.de\/service\/hotels\/deutschland\/nordrhein-westfalen\/minden\/\" rel=\"nofollow\" >Hotels in Minden<\/a><br \/>\n<a target=\"_blank\" href=\"https:\/\/www.weltweit-urlaub.de\/service\/hotels\/deutschland\/nordrhein-westfalen\/porta-westfalica\/\" rel=\"nofollow\" >Hotels in Porta Westfalica<\/a><br \/>\n<a target=\"_blank\" href=\"https:\/\/www.weltweit-urlaub.de\/service\/hotels\/deutschland\/nordrhein-westfalen\/bad-oeyn-hausen\/\" rel=\"nofollow\" >Hotels in Bad Oeynhausen<\/a><br \/>\n<a target=\"_blank\" href=\"https:\/\/www.weltweit-urlaub.de\/service\/hotels\/deutschland\/nordrhein-westfalen\/hille\/\" rel=\"nofollow\" >Hotels in Hille<\/a><br \/>\n<a target=\"_blank\" href=\"https:\/\/www.weltweit-urlaub.de\/service\/hotels\/deutschland\/luebbecke\/\" rel=\"nofollow\" >Hotels in L\u00fcbbecke <\/a><br \/>\n<a target=\"_blank\" href=\"https:\/\/www.weltweit-urlaub.de\/service\/hotels\/deutschland\/nordrhein-westfalen\/espelkamp\/\" rel=\"nofollow\" >Hotels in Espelkamp<\/a><br \/>\n<a target=\"_blank\" href=\"https:\/\/www.weltweit-urlaub.de\/service\/hotels\/deutschland\/nordrhein-westfalen\/petershagen\/\" rel=\"nofollow\" >Hotels in Petershagen<\/a><br \/>\n<a target=\"_blank\" href=\"https:\/\/www.weltweit-urlaub.de\/service\/hotels\/deutschland\/nordrhein-westfalen\/rahden\/\" rel=\"nofollow\" >Hotels in Rahden<\/a><br \/>\n<a target=\"_blank\" href=\"https:\/\/www.weltweit-urlaub.de\/service\/hotels\/deutschland\/nordrhein-westfalen\/stemwede\/\" rel=\"nofollow\" >Hotels in Stemwede<\/a><br \/>\n<a target=\"_blank\" href=\"https:\/\/www.weltweit-urlaub.de\/service\/hotels\/deutschland\/preussisch-oldendorf\/\" rel=\"nofollow\" >Hotels in Preu\u00dfisch Oldendorf<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir erreichen den Gro\u00dfen Stein \u00fcber die Stra\u00dfe Rahden &#8211; Diepenau im sch\u00f6nen M\u00fchlenkreis. In Tonnenheide &#8211; Heidkamp biegen wir am Wegweiser &#8222;Gro\u00dfer Stein&#8220; links ab. Es ist kaum zu glauben, aber es handelt sich tats\u00e4chlich um einen Findling aus Skandinavien. Dieser ist 10 m lang, 7 m breit und 3 m hoch. Sein Gewicht [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[87,1,45,289,96],"tags":[],"class_list":["post-7091","post","type-post","status-publish","format-standard","hentry","category-reiseberichte","category-urlaubsblog","category-deutschland","category-muehlenkreis","category-nordrhein-westfalen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Der Gro\u00dfe Stein von Tonnenheide - Reisebericht, Fotos, Urlaub &amp; Reise<\/title>\n<meta name=\"description\" content=\"Der Gro\u00dfe Stein von Tonnenheide - Weltweit Urlaub Blog - Urlaub und Kurzurlaub, Reisebericht \u00fcber Reise u. Urlaubsorte in Deutschland und Reiseziele in Europa und weltweit.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weltweit-urlaub.de\/blog\/der-grosse-stein-von-tonnenheide\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der Gro\u00dfe Stein von Tonnenheide - Reisebericht, Fotos, Urlaub &amp; Reise\" \/>\n<meta property=\"og:description\" content=\"Der Gro\u00dfe Stein von Tonnenheide - Weltweit Urlaub Blog - Urlaub und Kurzurlaub, Reisebericht \u00fcber Reise u. Urlaubsorte in Deutschland und Reiseziele in Europa und weltweit.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weltweit-urlaub.de\/blog\/der-grosse-stein-von-tonnenheide\/\" \/>\n<meta property=\"og:site_name\" content=\"Weltweit Urlaub Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Weltweit-Urlaub\/180623258643736\" \/>\n<meta property=\"article:published_time\" content=\"2011-11-04T08:39:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-03-05T15:47:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weltweit-urlaub.de\/blog\/wp-content\/uploads\/windmuehle-tonnenheide.jpg\" \/>\n<meta name=\"author\" content=\"Franz\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Franz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.weltweit-urlaub.de\/blog\/der-grosse-stein-von-tonnenheide\/\",\"url\":\"https:\/\/www.weltweit-urlaub.de\/blog\/der-grosse-stein-von-tonnenheide\/\",\"name\":\"Der Gro\u00dfe Stein von Tonnenheide - Reisebericht, Fotos, Urlaub & Reise\",\"isPartOf\":{\"@id\":\"https:\/\/www.weltweit-urlaub.de\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.weltweit-urlaub.de\/blog\/der-grosse-stein-von-tonnenheide\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.weltweit-urlaub.de\/blog\/der-grosse-stein-von-tonnenheide\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.weltweit-urlaub.de\/blog\/wp-content\/uploads\/windmuehle-tonnenheide.jpg\",\"datePublished\":\"2011-11-04T08:39:30+00:00\",\"dateModified\":\"2014-03-05T15:47:49+00:00\",\"author\":{\"@id\":\"https:\/\/www.weltweit-urlaub.de\/blog\/#\/schema\/person\/580334b794d1d84c44ed185071077fc3\"},\"description\":\"Der Gro\u00dfe Stein von Tonnenheide - Weltweit Urlaub Blog - Urlaub und Kurzurlaub, Reisebericht \u00fcber Reise u. Urlaubsorte in Deutschland und Reiseziele in Europa und weltweit.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.weltweit-urlaub.de\/blog\/der-grosse-stein-von-tonnenheide\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.weltweit-urlaub.de\/blog\/der-grosse-stein-von-tonnenheide\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.weltweit-urlaub.de\/blog\/der-grosse-stein-von-tonnenheide\/#primaryimage\",\"url\":\"https:\/\/www.weltweit-urlaub.de\/blog\/wp-content\/uploads\/windmuehle-tonnenheide.jpg\",\"contentUrl\":\"https:\/\/www.weltweit-urlaub.de\/blog\/wp-content\/uploads\/windmuehle-tonnenheide.jpg\",\"width\":\"450\",\"height\":\"338\",\"caption\":\"Windm\u00fchle Tonnenheide\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.weltweit-urlaub.de\/blog\/der-grosse-stein-von-tonnenheide\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.weltweit-urlaub.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Der Gro\u00dfe Stein von Tonnenheide\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.weltweit-urlaub.de\/blog\/#website\",\"url\":\"https:\/\/www.weltweit-urlaub.de\/blog\/\",\"name\":\"Weltweit Urlaub Blog\",\"description\":\"Das Weltweit Urlaub Blog berichtet von L\u00e4ndern, St\u00e4dten und Regionen rund um den Globus...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.weltweit-urlaub.de\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.weltweit-urlaub.de\/blog\/#\/schema\/person\/580334b794d1d84c44ed185071077fc3\",\"name\":\"Franz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.weltweit-urlaub.de\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/61e4c9d2e568c90c06cae6dfa71dc329?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/61e4c9d2e568c90c06cae6dfa71dc329?s=96&d=mm&r=g\",\"caption\":\"Franz\"},\"sameAs\":[\"https:\/\/www.weltweit-urlaub.de\/blog\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Der Gro\u00dfe Stein von Tonnenheide - Reisebericht, Fotos, Urlaub & Reise","description":"Der Gro\u00dfe Stein von Tonnenheide - Weltweit Urlaub Blog - Urlaub und Kurzurlaub, Reisebericht \u00fcber Reise u. Urlaubsorte in Deutschland und Reiseziele in Europa und weltweit.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weltweit-urlaub.de\/blog\/der-grosse-stein-von-tonnenheide\/","og_locale":"de_DE","og_type":"article","og_title":"Der Gro\u00dfe Stein von Tonnenheide - Reisebericht, Fotos, Urlaub & Reise","og_description":"Der Gro\u00dfe Stein von Tonnenheide - Weltweit Urlaub Blog - Urlaub und Kurzurlaub, Reisebericht \u00fcber Reise u. Urlaubsorte in Deutschland und Reiseziele in Europa und weltweit.","og_url":"https:\/\/www.weltweit-urlaub.de\/blog\/der-grosse-stein-von-tonnenheide\/","og_site_name":"Weltweit Urlaub Blog","article_publisher":"https:\/\/www.facebook.com\/pages\/Weltweit-Urlaub\/180623258643736","article_published_time":"2011-11-04T08:39:30+00:00","article_modified_time":"2014-03-05T15:47:49+00:00","og_image":[{"url":"https:\/\/www.weltweit-urlaub.de\/blog\/wp-content\/uploads\/windmuehle-tonnenheide.jpg","type":"","width":"","height":""}],"author":"Franz","twitter_misc":{"Verfasst von":"Franz","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.weltweit-urlaub.de\/blog\/der-grosse-stein-von-tonnenheide\/","url":"https:\/\/www.weltweit-urlaub.de\/blog\/der-grosse-stein-von-tonnenheide\/","name":"Der Gro\u00dfe Stein von Tonnenheide - Reisebericht, Fotos, Urlaub & Reise","isPartOf":{"@id":"https:\/\/www.weltweit-urlaub.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weltweit-urlaub.de\/blog\/der-grosse-stein-von-tonnenheide\/#primaryimage"},"image":{"@id":"https:\/\/www.weltweit-urlaub.de\/blog\/der-grosse-stein-von-tonnenheide\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weltweit-urlaub.de\/blog\/wp-content\/uploads\/windmuehle-tonnenheide.jpg","datePublished":"2011-11-04T08:39:30+00:00","dateModified":"2014-03-05T15:47:49+00:00","author":{"@id":"https:\/\/www.weltweit-urlaub.de\/blog\/#\/schema\/person\/580334b794d1d84c44ed185071077fc3"},"description":"Der Gro\u00dfe Stein von Tonnenheide - Weltweit Urlaub Blog - Urlaub und Kurzurlaub, Reisebericht \u00fcber Reise u. Urlaubsorte in Deutschland und Reiseziele in Europa und weltweit.","breadcrumb":{"@id":"https:\/\/www.weltweit-urlaub.de\/blog\/der-grosse-stein-von-tonnenheide\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weltweit-urlaub.de\/blog\/der-grosse-stein-von-tonnenheide\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weltweit-urlaub.de\/blog\/der-grosse-stein-von-tonnenheide\/#primaryimage","url":"https:\/\/www.weltweit-urlaub.de\/blog\/wp-content\/uploads\/windmuehle-tonnenheide.jpg","contentUrl":"https:\/\/www.weltweit-urlaub.de\/blog\/wp-content\/uploads\/windmuehle-tonnenheide.jpg","width":"450","height":"338","caption":"Windm\u00fchle Tonnenheide"},{"@type":"BreadcrumbList","@id":"https:\/\/www.weltweit-urlaub.de\/blog\/der-grosse-stein-von-tonnenheide\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.weltweit-urlaub.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Der Gro\u00dfe Stein von Tonnenheide"}]},{"@type":"WebSite","@id":"https:\/\/www.weltweit-urlaub.de\/blog\/#website","url":"https:\/\/www.weltweit-urlaub.de\/blog\/","name":"Weltweit Urlaub Blog","description":"Das Weltweit Urlaub Blog berichtet von L\u00e4ndern, St\u00e4dten und Regionen rund um den Globus...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weltweit-urlaub.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.weltweit-urlaub.de\/blog\/#\/schema\/person\/580334b794d1d84c44ed185071077fc3","name":"Franz","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.weltweit-urlaub.de\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/61e4c9d2e568c90c06cae6dfa71dc329?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61e4c9d2e568c90c06cae6dfa71dc329?s=96&d=mm&r=g","caption":"Franz"},"sameAs":["https:\/\/www.weltweit-urlaub.de\/blog\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.weltweit-urlaub.de\/blog\/wp-json\/wp\/v2\/posts\/7091"}],"collection":[{"href":"https:\/\/www.weltweit-urlaub.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weltweit-urlaub.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weltweit-urlaub.de\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weltweit-urlaub.de\/blog\/wp-json\/wp\/v2\/comments?post=7091"}],"version-history":[{"count":11,"href":"https:\/\/www.weltweit-urlaub.de\/blog\/wp-json\/wp\/v2\/posts\/7091\/revisions"}],"predecessor-version":[{"id":13242,"href":"https:\/\/www.weltweit-urlaub.de\/blog\/wp-json\/wp\/v2\/posts\/7091\/revisions\/13242"}],"wp:attachment":[{"href":"https:\/\/www.weltweit-urlaub.de\/blog\/wp-json\/wp\/v2\/media?parent=7091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weltweit-urlaub.de\/blog\/wp-json\/wp\/v2\/categories?post=7091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weltweit-urlaub.de\/blog\/wp-json\/wp\/v2\/tags?post=7091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}